{"id":23363,"date":"2023-08-17T13:43:39","date_gmt":"2023-08-17T11:43:39","guid":{"rendered":"https:\/\/www.wikeeps.com\/?p=23363"},"modified":"2023-09-21T10:53:41","modified_gmt":"2023-09-21T08:53:41","slug":"servire-il-vino-al-bicchiere","status":"publish","type":"post","link":"https:\/\/www.wikeeps.com\/it\/servire-il-vino-al-bicchiere\/","title":{"rendered":"Servire il vino al bicchiere"},"content":{"rendered":"<h2>Servire il vino al bicchiere con Wikeeps: un&#8217;esperienza eccezionale<\/h2>\n<p>Wikeeps, leader nella conservazione e nel servizio del vino al bicchiere, offre un&#8217;esperienza unica che garantisce la qualit\u00e0 e prolunga il piacere della degustazione. Grazie alle sue innovazioni all&#8217;avanguardia, Wikeeps ha portato il servizio del vino al bicchiere allo stato dell&#8217;arte.<\/p>\n<h3>1. La conservazione del vino: una garanzia di freschezza prolungata<\/h3>\n<p>Wikeeps r\u00e9pond aux trois composantes essentielles des moments de d\u00e9gustation. Tout d&#8217;abord, son syst\u00e8me de pr\u00e9servation permet de conserver le vin jusqu&#8217;\u00e0 3 semaines apr\u00e8s l&#8217;ouverture des bouteilles. Gr\u00e2ce \u00e0 l&#8217;utilisation d&#8217;un gaz \u0153nologique (m\u00e9lange d&#8217;Argon et de CO2), une atmosph\u00e8re protectrice est cr\u00e9\u00e9e au-dessus du vin \u00e0 chaque service, emp\u00eachant ainsi toute oxydation et alt\u00e9ration du vin.<\/p>\n<h3>2. La temperatura ideale per ogni bicchiere<\/h3>\n<p>La temperatura a cui viene servito il vino gioca un ruolo fondamentale nella degustazione. Con la sua gamma di Wibox, vetrine refrigerate progettate per uso domestico e professionale, Wikeeps garantisce che il vino al bicchiere sia servito alla temperatura ideale. Cos\u00ec ogni sorso \u00e8 un&#8217;esperienza di degustazione ottimale.<\/p>\n<h3>3. Servizio elegante e versatile<\/h3>\n<p>Il sistema Wikeeps si distingue anche per l&#8217;eleganza e la versatilit\u00e0 del servizio al bicchiere. Qualunque sia il formato della bottiglia, Wikeeps offre sistemi di servizio adatti a tutte le bottiglie, da 0,50 litri a 18 litri. Inoltre, questo sistema consente di servire il vino in verticale, mettendo in risalto le bottiglie e creando una presentazione elegante.<\/p>\n<p>&nbsp;<\/p>\n<h2>Mettete in mostra le vostre bottiglie con Wikeeps<\/h2>\n<p>Che si tratti di degustazioni, fiere o ricevimenti, Wikeeps \u00e8 l&#8217;alleato perfetto. Le bottiglie vengono messe in mostra attraverso un servizio verticale, offrendo una presentazione estetica che impressioner\u00e0 i vostri ospiti. Combinando l&#8217;uso di Wibox per mantenere il vino alla temperatura ideale e valorizzare le etichette delle bottiglie, avrete tutti gli elementi necessari per un servizio al bicchiere completo e raffinato.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-15331 size-large\" src=\"https:\/\/www.wikeeps.com\/wp-content\/uploads\/\" alt=\"Mini cave a vin Wikeeps\" width=\"1024\" height=\"683\" \/><\/p>\n<p style=\"text-align: center;\"><strong><a class=\"sr-button style-1 button-normal\" style=\"background-color: red; color: white;\" href=\"https:\/\/www.wikeeps.com\/it\/innovazione-wikeeps-conservazione-del-vino\/\">D\u00e9couvrez l\u2019innovation Wibox<\/a><\/strong><\/p>\n<h2><\/h2>\n<h2>Un servizio semplice ed elegante a portata di mano<\/h2>\n<p>Wikeeps rende il servizio del vino al bicchiere unico ed elegante. Basta premere il grilletto della pistola e la magia si compie. <a href=\"https:\/\/www.wikeeps.com\/it\/compatibilita-capsule-wikeeps-e-sistema-coravin\/\"><strong>Il gas enologico<\/strong><\/a> entra nella bottiglia, prendendo il posto dell&#8217;aria, e permette al vino di salire fino al bicchiere. A casa, al ristorante o in un&#8217;enoteca, i prodotti Wikeeps vi daranno la massima soddisfazione offrendovi il servizio ideale del vino al bicchiere.<\/p>\n<p>&nbsp;<\/p>\n<h2>Scoprite l&#8217;intera gamma su Wikeeps.it<\/h2>\n<p>Per esplorare l&#8217;intera gamma di prodotti offerti da Wikeeps, visitate il sito web Wikeeps.co.it. Troverete anche la nostra offerta speciale per aiutarvi a ottenere il massimo dall&#8217;esperienza del vino al bicchiere. Unitevi alla comunit\u00e0 di Wikeeps e seguiteci su Facebook, Twitter e Instagram per essere sempre aggiornati sulle nostre novit\u00e0 nel mondo del vino al bicchiere. A presto!<\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: 6px; top: 1464.25px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Servire il vino al bicchiere con Wikeeps: un&#8217;esperienza eccezionale Wikeeps, leader nella conservazione e nel servizio del vino al bicchiere, offre un&#8217;esperienza unica che garantisce la qualit\u00e0 e prolunga il piacere della degustazione. Grazie alle sue innovazioni all&#8217;avanguardia, Wikeeps ha portato il servizio del vino al bicchiere allo stato dell&#8217;arte. 1. La conservazione del vino: [&hellip;]<\/p>\n","protected":false},"author":551,"featured_media":22274,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[306,300,301,429,302],"tags":[376],"class_list":["post-23363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-proposito-di-wikeeps","category-gaz-oenologique-it","category-miscela-del-vino","category-tecnologia-del-vino","category-vin-au-verre-it","tag-wikeeps-fr-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servire il vino al bicchiere - Wikeeps<\/title>\n<meta name=\"description\" content=\"Scopri l&#039;eccezionale visione di Wikeeps per servire il vino al bicchiere, unendo eleganza e conservazione\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wikeeps.com\/it\/servire-il-vino-al-bicchiere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servire il vino al bicchiere - Wikeeps\" \/>\n<meta property=\"og:description\" content=\"Scopri l&#039;eccezionale visione di Wikeeps per servire il vino al bicchiere, unendo eleganza e conservazione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wikeeps.com\/it\/servire-il-vino-al-bicchiere\/\" \/>\n<meta property=\"og:site_name\" content=\"Wikeeps\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wikeepsFr\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-17T11:43:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-21T08:53:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wikeeps.com\/wp-content\/uploads\/2023\/05\/pexels-pixabay-290316-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laurent Prigent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WIKEEPS\" \/>\n<meta name=\"twitter:site\" content=\"@WIKEEPS\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laurent Prigent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/servire-il-vino-al-bicchiere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/servire-il-vino-al-bicchiere\\\/\"},\"author\":{\"name\":\"Laurent Prigent\",\"@id\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/#\\\/schema\\\/person\\\/9533d59e9a6af1774531ac1bc57e4ba9\"},\"headline\":\"Servire il vino al bicchiere\",\"datePublished\":\"2023-08-17T11:43:39+00:00\",\"dateModified\":\"2023-09-21T08:53:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/servire-il-vino-al-bicchiere\\\/\"},\"wordCount\":474,\"publisher\":{\"@id\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/servire-il-vino-al-bicchiere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wikeeps.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/pexels-pixabay-290316-scaled.jpg\",\"keywords\":[\"wikeeps\"],\"articleSection\":[\"A proposito di Wikeeps\",\"Gaz oenologique\",\"Mescita del vino\",\"tecnologia del vino\",\"Vin au verre\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/servire-il-vino-al-bicchiere\\\/\",\"url\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/servire-il-vino-al-bicchiere\\\/\",\"name\":\"Servire il vino al bicchiere - Wikeeps\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/servire-il-vino-al-bicchiere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/servire-il-vino-al-bicchiere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wikeeps.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/pexels-pixabay-290316-scaled.jpg\",\"datePublished\":\"2023-08-17T11:43:39+00:00\",\"dateModified\":\"2023-09-21T08:53:41+00:00\",\"description\":\"Scopri l'eccezionale visione di Wikeeps per servire il vino al bicchiere, unendo eleganza e conservazione\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/servire-il-vino-al-bicchiere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/servire-il-vino-al-bicchiere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/servire-il-vino-al-bicchiere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.wikeeps.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/pexels-pixabay-290316-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wikeeps.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/pexels-pixabay-290316-scaled.jpg\",\"width\":2048,\"height\":1365,\"caption\":\"\u00c9volution de la consommation mondiale du vin : Tendances et perspectives\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/servire-il-vino-al-bicchiere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/vino-al-calice\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servire il vino al bicchiere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/\",\"name\":\"Wikeeps\",\"description\":\"Service, a\u00e9ration et conservation | vin au verre\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/#organization\",\"name\":\"Wikeeps\",\"url\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.wikeeps.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Logo-Wikeeps.png\",\"contentUrl\":\"https:\\\/\\\/www.wikeeps.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Logo-Wikeeps.png\",\"width\":1000,\"height\":184,\"caption\":\"Wikeeps\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wikeepsFr\",\"https:\\\/\\\/x.com\\\/WIKEEPS\",\"https:\\\/\\\/www.instagram.com\\\/wikeeps\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.wikeeps.com\\\/it\\\/#\\\/schema\\\/person\\\/9533d59e9a6af1774531ac1bc57e4ba9\",\"name\":\"Laurent Prigent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02724f4a511dc2b29adea07e86ba232e43d2c6bc729f4b66504f2bc698619e16?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02724f4a511dc2b29adea07e86ba232e43d2c6bc729f4b66504f2bc698619e16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02724f4a511dc2b29adea07e86ba232e43d2c6bc729f4b66504f2bc698619e16?s=96&d=mm&r=g\",\"caption\":\"Laurent Prigent\"},\"sameAs\":[\"https:\\\/\\\/wikeeps.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servire il vino al bicchiere - Wikeeps","description":"Scopri l'eccezionale visione di Wikeeps per servire il vino al bicchiere, unendo eleganza e conservazione","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wikeeps.com\/it\/servire-il-vino-al-bicchiere\/","og_locale":"it_IT","og_type":"article","og_title":"Servire il vino al bicchiere - Wikeeps","og_description":"Scopri l'eccezionale visione di Wikeeps per servire il vino al bicchiere, unendo eleganza e conservazione","og_url":"https:\/\/www.wikeeps.com\/it\/servire-il-vino-al-bicchiere\/","og_site_name":"Wikeeps","article_publisher":"https:\/\/www.facebook.com\/wikeepsFr","article_published_time":"2023-08-17T11:43:39+00:00","article_modified_time":"2023-09-21T08:53:41+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/www.wikeeps.com\/wp-content\/uploads\/2023\/05\/pexels-pixabay-290316-scaled.jpg","type":"image\/jpeg"}],"author":"Laurent Prigent","twitter_card":"summary_large_image","twitter_creator":"@WIKEEPS","twitter_site":"@WIKEEPS","twitter_misc":{"Scritto da":"Laurent Prigent","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wikeeps.com\/it\/servire-il-vino-al-bicchiere\/#article","isPartOf":{"@id":"https:\/\/www.wikeeps.com\/it\/servire-il-vino-al-bicchiere\/"},"author":{"name":"Laurent Prigent","@id":"https:\/\/www.wikeeps.com\/it\/#\/schema\/person\/9533d59e9a6af1774531ac1bc57e4ba9"},"headline":"Servire il vino al bicchiere","datePublished":"2023-08-17T11:43:39+00:00","dateModified":"2023-09-21T08:53:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wikeeps.com\/it\/servire-il-vino-al-bicchiere\/"},"wordCount":474,"publisher":{"@id":"https:\/\/www.wikeeps.com\/it\/#organization"},"image":{"@id":"https:\/\/www.wikeeps.com\/it\/servire-il-vino-al-bicchiere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wikeeps.com\/wp-content\/uploads\/2023\/05\/pexels-pixabay-290316-scaled.jpg","keywords":["wikeeps"],"articleSection":["A proposito di Wikeeps","Gaz oenologique","Mescita del vino","tecnologia del vino","Vin au verre"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.wikeeps.com\/it\/servire-il-vino-al-bicchiere\/","url":"https:\/\/www.wikeeps.com\/it\/servire-il-vino-al-bicchiere\/","name":"Servire il vino al bicchiere - Wikeeps","isPartOf":{"@id":"https:\/\/www.wikeeps.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wikeeps.com\/it\/servire-il-vino-al-bicchiere\/#primaryimage"},"image":{"@id":"https:\/\/www.wikeeps.com\/it\/servire-il-vino-al-bicchiere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wikeeps.com\/wp-content\/uploads\/2023\/05\/pexels-pixabay-290316-scaled.jpg","datePublished":"2023-08-17T11:43:39+00:00","dateModified":"2023-09-21T08:53:41+00:00","description":"Scopri l'eccezionale visione di Wikeeps per servire il vino al bicchiere, unendo eleganza e conservazione","breadcrumb":{"@id":"https:\/\/www.wikeeps.com\/it\/servire-il-vino-al-bicchiere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wikeeps.com\/it\/servire-il-vino-al-bicchiere\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.wikeeps.com\/it\/servire-il-vino-al-bicchiere\/#primaryimage","url":"https:\/\/www.wikeeps.com\/wp-content\/uploads\/2023\/05\/pexels-pixabay-290316-scaled.jpg","contentUrl":"https:\/\/www.wikeeps.com\/wp-content\/uploads\/2023\/05\/pexels-pixabay-290316-scaled.jpg","width":2048,"height":1365,"caption":"\u00c9volution de la consommation mondiale du vin : Tendances et perspectives"},{"@type":"BreadcrumbList","@id":"https:\/\/www.wikeeps.com\/it\/servire-il-vino-al-bicchiere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.wikeeps.com\/it\/vino-al-calice\/"},{"@type":"ListItem","position":2,"name":"Servire il vino al bicchiere"}]},{"@type":"WebSite","@id":"https:\/\/www.wikeeps.com\/it\/#website","url":"https:\/\/www.wikeeps.com\/it\/","name":"Wikeeps","description":"Service, a\u00e9ration et conservation | vin au verre","publisher":{"@id":"https:\/\/www.wikeeps.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wikeeps.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.wikeeps.com\/it\/#organization","name":"Wikeeps","url":"https:\/\/www.wikeeps.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.wikeeps.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.wikeeps.com\/wp-content\/uploads\/2025\/01\/Logo-Wikeeps.png","contentUrl":"https:\/\/www.wikeeps.com\/wp-content\/uploads\/2025\/01\/Logo-Wikeeps.png","width":1000,"height":184,"caption":"Wikeeps"},"image":{"@id":"https:\/\/www.wikeeps.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wikeepsFr","https:\/\/x.com\/WIKEEPS","https:\/\/www.instagram.com\/wikeeps\/"]},{"@type":"Person","@id":"https:\/\/www.wikeeps.com\/it\/#\/schema\/person\/9533d59e9a6af1774531ac1bc57e4ba9","name":"Laurent Prigent","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/02724f4a511dc2b29adea07e86ba232e43d2c6bc729f4b66504f2bc698619e16?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02724f4a511dc2b29adea07e86ba232e43d2c6bc729f4b66504f2bc698619e16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02724f4a511dc2b29adea07e86ba232e43d2c6bc729f4b66504f2bc698619e16?s=96&d=mm&r=g","caption":"Laurent Prigent"},"sameAs":["https:\/\/wikeeps.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.wikeeps.com\/it\/wp-json\/wp\/v2\/posts\/23363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wikeeps.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wikeeps.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wikeeps.com\/it\/wp-json\/wp\/v2\/users\/551"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wikeeps.com\/it\/wp-json\/wp\/v2\/comments?post=23363"}],"version-history":[{"count":0,"href":"https:\/\/www.wikeeps.com\/it\/wp-json\/wp\/v2\/posts\/23363\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wikeeps.com\/it\/wp-json\/wp\/v2\/media\/22274"}],"wp:attachment":[{"href":"https:\/\/www.wikeeps.com\/it\/wp-json\/wp\/v2\/media?parent=23363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wikeeps.com\/it\/wp-json\/wp\/v2\/categories?post=23363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wikeeps.com\/it\/wp-json\/wp\/v2\/tags?post=23363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}